{"id":865,"date":"2019-12-23T16:56:05","date_gmt":"2019-12-23T19:56:05","guid":{"rendered":"http:\/\/www.acaoparamita.com.br\/?p=865"},"modified":"2025-07-13T09:31:31","modified_gmt":"2025-07-13T12:31:31","slug":"o-caminho-da-meditacao","status":"publish","type":"post","link":"https:\/\/acaoparamita.com.br\/en\/o-caminho-da-meditacao\/","title":{"rendered":"Thematic course \u2013 <br>\"The Path of Meditation\"<\/br>"},"content":{"rendered":"<p><amp-fit-text layout=\"fixed-height\" min-font-size=\"6\" max-font-size=\"72\" height=\"80\">Nessa linha tem\u00e1tica voc\u00ea encontrar\u00e1 instru\u00e7\u00f5es diretas para ter \u00eaxito no caminho da medita\u00e7\u00e3o e evitar os obst\u00e1culos naturais. Esses \u00e1udios foram gravados durante o retiro da Ilumina\u00e7\u00e3o do Buda de 01 a 08 de dezembro de 2019 no Cebb Caminho do Meio em Viam\u00e3o. O objetivo \u00e9 apoiar os praticantes que, de v\u00e1rios modos e em v\u00e1rias circunst\u00e2ncias diferentes tenham feito contato com os ensinamentos budistas, desejem agora aprofundar no caminho do treinamento e obter resultados claros. Na linguagem do Cebb, s\u00e3o os praticantes que buscam aprofundar no bloco dois dos ensinamentos.<\/amp-fit-text><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Nas grava\u00e7\u00f5es h\u00e1 os sons naturais do ambiente, incluindo o gorgeio de p\u00e1ssaros que rodeiam o templo do Caminho do Meio.<\/em><\/p>\n\n\n\n<h2>Como usar os conte\u00fados dessa linha tem\u00e1tica<\/h2>\n\n\n\n<p>A melhor op\u00e7\u00e3o \u00e9 seguir os conte\u00fados de modo organizado, com hor\u00e1rios pr\u00e9-definidos, iniciar com as preces de ref\u00fagio, recitar os mantras do Guru e de Prajnaparamita, manter 30 minutos de Shamata, estudar e contemplar os conte\u00fados no tempo que puder dispor, finalizar com as preces de dedica\u00e7\u00e3o. Os conte\u00fados devem ser visitados sucessivamente de modo circular, ou seja, ao final do \u00faltimo cap\u00edtulo retomar desde o primeiro por pelo menos tr\u00eas vezes.\nA contempla\u00e7\u00e3o \u00e9 algo crucial e transformador, assim deveria ser entendido que o n\u00e9ctar das instru\u00e7\u00f5es e vis\u00f5es que o Buda apresentou a n\u00f3s deveria ser bebido diretamente e a contempla\u00e7\u00e3o \u00e9 a forma indicada por ele para tal.\nCaso aspire engajar-se em retiros m\u00e9dios e longos, deveria realmente dedicar-se previamente a contemplar e praticar dentro dessa linha tem\u00e1tica.<\/p>\n\n\n\n<h2><a name=\"voltar\">\u00cdndice <\/h2>\n<a href=\"#capitulo_1\">Cap\u00edtulo 1 &#8211; Contexto Contempor\u00e2neo e seus Desafios<\/a><br>\n<a href=\"#capitulo_2\">Cap\u00edtulo 2 &#8211; A Primeira Nobre Verdade, Medita\u00e7\u00e3o, Origina\u00e7\u00e3o Dependente, Liberdade e Contempla\u00e7\u00e3o<\/a><br>\n<a href=\"#capitulo_3\">Cap\u00edtulo 3 &#8211; A Pr\u00e1tica da Contempla\u00e7\u00e3o <\/a><br>\n<a href=\"#capitulo_4\">Cap\u00edtulo 4 &#8211; A Roda da Vida e os Seis Reinos <\/a><br>\n<a href=\"#capitulo_5\">Cap\u00edtulo 5 &#8211; A Roda da Vida, Os Doze Elos e o Caminho do Bodisatva <\/a><br>\n<a href=\"#capitulo_6\">Cap\u00edtulo 6 &#8211; A Import\u00e2ncia de Contemplar as Tr\u00eas Primeiras Nobres Verdades  <\/a><br>\n<a href=\"#capitulo_7\">Cap\u00edtulo 7 &#8211; O Caminho Internalizador<\/a><br>\n<a href=\"#capitulo_8\">Cap\u00edtulo 8 &#8211; Primeiro ao Quinto Passo do Nobre Caminho de Oito Passos \u2013 Requisitos para Retiros<\/a><br>\n<a href=\"#capitulo_9\">Cap\u00edtulo 9 &#8211; Quinto Passo do Nobre Caminho de Oito Passos \u2013 Bodicita<\/a><br>\n<a href=\"#capitulo_10\">Cap\u00edtulo 10 &#8211; Vis\u00e3o de Terra Pura<\/a><br>\n<a href=\"#capitulo_11\">Cap\u00edtulo 11 &#8211; Sexto Passo do Nobre Caminho \u2013 Shamata<\/a><br>\n<a href=\"#capitulo_12\">Cap\u00edtulo 12 &#8211; Vis\u00e3o do Caminho e Extin\u00e7\u00e3o<\/a><br>\n<a href=\"#capitulo_13\">Cap\u00edtulo 13 &#8211; Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 Vis\u00e3o<\/a><br>\n<a href=\"#capitulo_14\">Cap\u00edtulo 14 &#8211; Contextualiza\u00e7\u00e3o do Estudo<\/a><br>\n<a href=\"#capitulo_15\">Cap\u00edtulo 15 &#8211; Contextualiza\u00e7\u00e3o do Trajeto Percorrido<\/a><br>\n<a href=\"#capitulo_16\">Cap\u00edtulo 16 &#8211; Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 Medita\u00e7\u00e3o<\/a><br>\n<a href=\"#capitulo_17\">Cap\u00edtulo 17 &#8211; Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 A\u00e7\u00e3o<\/a><br>\n<a href=\"#capitulo_18\">Cap\u00edtulo 18 &#8211; Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 Frui\u00e7\u00e3o<\/a><br>\n<a href=\"#capitulo_19\">Cap\u00edtulo 19 &#8211; A Motiva\u00e7\u00e3o e o Caminho<\/a><br>\n<a href=\"#capitulo_20\">Cap\u00edtulo 20 &#8211; As Crises Desafiadoras Atuais<\/a><br>\n\n\n\n<h3><a name=\"capitulo_1\"><\/a> <u>Cap\u00edtulo 1<\/u> <\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Contexto Contempor\u00e2neo e seus Desafios <\/h3>\n\n\n\n<p>Muitos diferentes ensinamentos foram oferecidos pelo Buda e\npor grandes mestres subsequentes a ele. Presentemente esses ensinamentos se\nencontram com um mundo aparente muito diferente das vis\u00f5es antigas com as quais\no budismo j\u00e1 se encontrou. Nesse cap\u00edtulo inicial vamos descrever a perspectiva\nde unidade e profundidade dos ensinamentos, onde os aspectos introdut\u00f3rios e os\naspectos \u00faltimos est\u00e3o integrados em suas qualidades e capacidades de produzir\nbenef\u00edcios.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758182849%3Fsecret_token%3Ds-BDxJfK3qyo7&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<p><\/p>\n\n\n\n<h3><a name=\"capitulo_2\"><\/a> <u>Cap\u00edtulo 2<\/u> <\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A Primeira Nobre Verdade, Medita\u00e7\u00e3o, Origina\u00e7\u00e3o Dependente, Liberdade e Contempla\u00e7\u00e3o<\/h3>\n\n\n\n<p>O Buda enfatiza diretamente a contempla\u00e7\u00e3o da realidade circundante e tamb\u00e9m do corpo, dos estados emocionais e da mente. A \u00eanfase na medita\u00e7\u00e3o surgir\u00e1 mais adiante, na quarta nobre verdade, dentro do sexto passo do nobre caminho de oito passos.<\/p>\n\n\n\n<p>Na linguagem do Cebb, para termos \u00eaxito no caminho da medita\u00e7\u00e3o e da lucidez, precisamos ultrapassar as bolhas que produzem o samsara, ou seja, o envolvente sentido confuso da realidade. A contempla\u00e7\u00e3o da roda da vida em suas v\u00e1rias partes e da primeira nobre verdade nos habilita a quebrar o automatismo desavisado com respeito \u00e0s apar\u00eancias externas e \u00e0s vis\u00f5es e disposi\u00e7\u00f5es internas.<\/p>\n\n\n\n<p>Ainda que o Buda nos apresente vis\u00f5es elevadas e libertadoras, seus ensinamentos nos conduzem a desenvolver essas vis\u00f5es de modo verdadeiramente aut\u00f4nomo atrav\u00e9s da contempla\u00e7\u00e3o. <\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758183662%3Fsecret_token%3Ds-4He3iCBKJ85&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_3\"><\/a><u>Cap\u00edtulo 3<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A Pr\u00e1tica da Contempla\u00e7\u00e3o <\/h3>\n\n\n\n<p>Caminho Internalizador e Caminho Externalizador, como olhar para dentro.  Esses ensinamentos nos colocam no lugar onde o Buda desenvolveu suas vis\u00f5es e passamos a ver da forma como ele descreve \u2013 a isso chamamos contempla\u00e7\u00e3o. <\/p>\n\n\n\n<p>Se entendermos os ensinamentos do Buda, teremos grande benef\u00edcio, entretanto se n\u00e3o os contemplarmos encontrando a verdade desses ensinamentos diretamente nas apar\u00eancias com as quais lidamos, estaremos desabilitados para sustentar a lucidez em meio a vida. <\/p>\n\n\n\n<p>A contempla\u00e7\u00e3o \u00e9 a grande pr\u00e1tica de transforma\u00e7\u00e3o tanto interna como externa, ou seja, o pr\u00f3prio mundo como o experimentamos. <\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758185861%3Fsecret_token%3Ds-6Vqgbo7pNvx&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_4\"><\/a> <u>Cap\u00edtulo 4 <\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A Roda da Vida e os Seis Reinos<\/h3>\n\n\n\n<p>Sofrimento sensorial e sofrimento estrutural. O Samsara \u00e9 a apresenta\u00e7\u00e3o da luminosidade da mente e energia brotando da natureza livre incessantemente presente. Os seis reinos surgem como experi\u00eancia natural dos seres correspondentes e seus focos estreitos. Todos os reinos s\u00e3o produzidos do mesmo modo, com o mesmo material luminoso. <\/p>\n\n\n\n<p>Os reinos s\u00e3o naturalmente surgidos como experi\u00eancias psic\u00f3ticas cujos seres n\u00e3o percebem suas limita\u00e7\u00f5es e apenas buscam transmigrar para outras experi\u00eancias que surgem como ambientes externos. Isso se aplica a todas formas de experi\u00eancia dos mundos como os entendemos de modo convencional. <\/p>\n\n\n\n<p>\u00c9 uma quest\u00e3o ampla que trata de lucidez e liberdade, n\u00e3o \u00e9 uma quest\u00e3o religiosa \u2013 podemos acessar esses ensinamentos na perspectiva da verdadeira educa\u00e7\u00e3o libertadora. <\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758197381%3Fsecret_token%3Ds-Y1XtXaariSf&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_5\"><\/a> <u> Cap\u00edtulo 5 <\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A Roda da Vida, Os Doze Elos e o Caminho do Bodisatva<\/h3>\n\n\n\n<p>A vacuidade e a luminosidade produzindo os mundos luminosos em sua multiplicidade. O surgimento da ignor\u00e2ncia avydia e seu desdobramento progressivo. O estabelecimento da experi\u00eancia individual em doze elos. <\/p>\n\n\n\n<p>A inevit\u00e1vel frustra\u00e7\u00e3o proveniente da busca pelos mundos de felicidade e n\u00e3o sofrimento, e pelo engajamento em sucessivos processos de transmigra\u00e7\u00e3o. A lucidez frente a situa\u00e7\u00e3o de todos os seres \u00e9 a base para o nascimento do Bodisatva. <\/p>\n\n\n\n<p>Havendo esse nascimento, os Bodisatvas se engajam em a\u00e7\u00f5es merit\u00f3rias e naturalmente ficam livres dos impulsos que originariam a\u00e7\u00f5es n\u00e3o virtuosas. As cinco sabedorias, as quatro qualidades incomensur\u00e1veis e as seis perfei\u00e7\u00f5es s\u00e3o a ess\u00eancia da manifesta\u00e7\u00e3o dos Bodisatvas. <\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758202853%3Fsecret_token%3Ds-Sl2MoVXNvo9&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_6\"><\/a>  <u>Cap\u00edtulo 6<\/u> <\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A Import\u00e2ncia de Contemplar as Tr\u00eas Primeiras Nobres Verdades <\/h3>\n\n\n\n<p>A contempla\u00e7\u00e3o das Tr\u00eas Primeiras Nobres Verdades enunciadas pelo Buda produzem a vis\u00e3o profunda e l\u00facida frente ao Samsara, trazem o vislumbre da natureza \u00faltima, condi\u00e7\u00f5es indispens\u00e1veis para o nascimento do Bodisatva e seu caminho iluminador. N\u00e3o havendo esse amadurecimento da contempla\u00e7\u00e3o das tr\u00eas primeiras nobres verdades, o caminho da medita\u00e7\u00e3o fica obstaculizado. <\/p>\n\n\n\n<p>O caminho n\u00e3o progredir\u00e1 efetivamente se nossa vis\u00e3o de mundo for a vis\u00e3o comum dentro da qual surgem e s\u00e3o acolhidos os impulsos usuais do Samsara. <\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758204212%3Fsecret_token%3Ds-b4iADVjXDuY&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_7\"><\/a><u> Cap\u00edtulo 7<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">O Caminho Internalizador<\/h3>\n\n\n\n<p>A grande import\u00e2ncia da contempla\u00e7\u00e3o das v\u00e1rias experi\u00eancias usualmente tidas como comuns e que justo por isso, guardam em si respostas automatizadas que nos reconectam ao Samsara. <\/p>\n\n\n\n<p>A naturalidade e o aparente bom senso de seu surgimento e opera\u00e7\u00e3o faz com que essa reconex\u00e3o ao Samsara seja produzida sem que nos demos conta disso. A contempla\u00e7\u00e3o dessas experi\u00eancias desde a vis\u00e3o internalizadora, incluindo nosso pr\u00f3prio corpo, suas partes, suas sensa\u00e7\u00f5es, tend\u00eancias e prioridades, bem como as apar\u00eancias vistas como externas, \u00e9 essencial para que possamos iluminar os obst\u00e1culos dos impulsos automatizados, energias condicionadas, e ent\u00e3o progredir no Nobre Caminho de Oito Passos.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758206336%3Fsecret_token%3Ds-f8Cfq9kvQpY&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_8\"><\/a> <u>Cap\u00edtulo 8 <\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Primeiro ao Quinto Passo do Nobre Caminho de Oito Passos \u2013 Requisitos para Retiros<\/h3>\n\n\n\n<p>A maturidade da compreens\u00e3o da origem dos obst\u00e1culos \u00e0 vis\u00e3o l\u00facida e ao surgimento do Samsara, d\u00e1 origem \u00e0 certeza com respeito a possibilidade de libera\u00e7\u00e3o e ilumina\u00e7\u00e3o. Como resultado brota a clareza da falta de sentido em buscar as metas e objetivos das vis\u00f5es limitadas. Isso n\u00e3o \u00e9 uma idealiza\u00e7\u00e3o e nem \u00e9 uma teoria, \u00e9 uma realiza\u00e7\u00e3o natural. Disso surge Bodicita, surgem os Bodisatvas sobre um l\u00f3tus enraizado no lago do sofrimento e das emo\u00e7\u00f5es perturbadoras, Bodisatvas que seguir\u00e3o por completo o caminho at\u00e9 o resultado final. <\/p>\n\n\n\n<p>O funcionamento da energia passa a operar diretamente desde a natureza livre da mente como manifesta\u00e7\u00e3o de Bodicita e n\u00e3o mais na depend\u00eancia dos doze elos da origina\u00e7\u00e3o dependente, atrav\u00e9s dos vedanas. Isso em si j\u00e1 \u00e9 uma libera\u00e7\u00e3o. Atrav\u00e9s de Bodicita o Bodisatva segue o caminho do primeiro ao quinto passo do nobre caminho, naturalmente, sem esfor\u00e7o, evita as a\u00e7\u00f5es negativas e promove as a\u00e7\u00f5es positivas. Essa realiza\u00e7\u00e3o se torna uma exig\u00eancia para a sequ\u00eancia do caminho. Na falta disso, o praticante fica vulner\u00e1vel a fixar-se novamente ao Samsara e suas identidades luminosas, sem entender a raz\u00e3o pela qual perde sua aparente realiza\u00e7\u00e3o.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758212408%3Fsecret_token%3Ds-zhcXEdAa6px&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_9\"><\/a> <u> Cap\u00edtulo 9 <\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Quinto Passo do Nobre Caminho de Oito Passos \u2013 Bodicita<\/h3>\n\n\n\n<p>A maturidade da compreens\u00e3o da origem dos obst\u00e1culos \u00e0 vis\u00e3o l\u00facida e do surgimento do Samsara, d\u00e1 surgimento \u00e0 mente Bodicita. A a\u00e7\u00e3o em meio ao mundo converge para as cinco sabedorias, as quatro qualidades incomensur\u00e1veis e as seis perfei\u00e7\u00f5es. <\/p>\n\n\n\n<p>A roda da vida e a a\u00e7\u00e3o baseada nos doze elos e nas dez a\u00e7\u00f5es n\u00e3o virtuosas perde o poder de produzir confus\u00e3o e sua energia se reduz. O brilho compassivo sustenta o cora\u00e7\u00e3o do praticante e sua vontade de compreender em profundidade todas as experi\u00eancias e verdadeiramente desenraizar os impulsos aflitivos sustenta sua a\u00e7\u00e3o e sua energia. O praticante verdadeiramente gera m\u00e9ritos e evita criar sofrimentos.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758215498%3Fsecret_token%3Ds-x9NPlol16pr&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_10\"><\/a> <u>Cap\u00edtulo 10 <\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Vis\u00e3o de Terra Pura<\/h3>\n\n\n\n<p>Descri\u00e7\u00e3o do que foi feito at\u00e9 agora e que compreens\u00e3o foi desenvolvida. O Buda nos apresentou aspectos de como a realidade interna e externa opera em nossas vidas. Nos colocou na posi\u00e7\u00e3o de observadores de n\u00f3s mesmos. Seguimos o caminho internalizador, entendendo o mundo interno e passando a dispor dos elementos que encontramos. Surgiu uma outra vis\u00e3o de mundo, uma terra pura, advinda da compreens\u00e3o profunda das nossas vidas. <\/p>\n\n\n\n<p>\u00c9 dentro dessa terra pura que faremos as pr\u00e1ticas de medita\u00e7\u00e3o. Se praticarmos dentro das bolhas usuais da roda da vida n\u00e3o teremos \u00eaxito. Quando o Buda descreve a roda da vida, ele fala desde o local livre que tamb\u00e9m est\u00e1 dispon\u00edvel para n\u00f3s \u2013 esse \u00e9 o ensinamento secreto que ele d\u00e1 pelo pr\u00f3prio exemplo. Ele descreve o que nos ensinamentos de Garab Dorje chama-se de Vis\u00e3o, que evolui para Medita\u00e7\u00e3o, A\u00e7\u00e3o e Frui\u00e7\u00e3o.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758216935%3Fsecret_token%3Ds-S19dKRZbHpt&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_11\"><\/a> <u>Cap\u00edtulo 11<\/u> <\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Sexto Passo do Nobre Caminho &#8211; Shamata<\/h3>\n\n\n\n<p>Nosso objetivo \u00e9 avan\u00e7ar em dire\u00e7\u00e3o ao s\u00e9timo passo. Precisamos inicialmente remover o obst\u00e1culo de ver a medita\u00e7\u00e3o como objetivo em si mesmo. Os ensinamentos do Buda sobre a respira\u00e7\u00e3o introspectiva nos ajudam a aprofundar a experi\u00eancia de lucidez no caminho internalizador. S\u00e3o guias de contempla\u00e7\u00e3o que nos ajudam a ver internamente e manter a liberdade de seguir ou n\u00e3o seguir os impulsos que surgem junto com as vis\u00f5es. <\/p>\n\n\n\n<p>\u00c9 o exerc\u00edcio da liberdade natural, presente sem conte\u00fado dual, vazia, luminosa, criadora, l\u00facida, al\u00e9m de liga\u00e7\u00e3o, rejei\u00e7\u00e3o ou indiferen\u00e7a com respeito as apar\u00eancias. Esse processo profundo inicia quando sentados serenos, inspiramos e expiramos e nos tornamos conscientes dos conte\u00fados internos e externos insepar\u00e1veis, um a um, calmamente. Assim praticamos o sentar calmo e l\u00facido de todos os Budas.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758218852%3Fsecret_token%3Ds-3z1VVG07JjZ&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_12\"><\/a> <u> Cap\u00edtulo 12<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Vis\u00e3o do Caminho e Extin\u00e7\u00e3o<\/h3>\n\n\n\n<p>Como se d\u00e3o as v\u00e1rias etapas do caminho, uma possibilitando a outra atrav\u00e9s da amplia\u00e7\u00e3o progressiva da vis\u00e3o que serve de base para a amplia\u00e7\u00e3o subsequente. Adotamos as quatro Nobres Verdades e o Nobre Caminho de Oito Passos como a linha tem\u00e1tica do caminho e os v\u00e1rios ensinamentos adicionais de outros mestres e ensinamentos mais recentes s\u00e3o inclu\u00eddos como coment\u00e1rios e extens\u00f5es que visam detalhar.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 suficiente que a vis\u00e3o do Buda chegue a n\u00f3s como uma informa\u00e7\u00e3o. \u00c9 passada a n\u00f3s como uma vis\u00e3o que ser\u00e1 copiada enquanto um m\u00e9todo para n\u00f3s mesmos passarmos a ver diretamente. Por vezes ficamos limitados ao que ouvimos e o respeito e devo\u00e7\u00e3o que desenvolvemos parece o suficiente. Em verdade o Buda nos convida a n\u00f3s mesmos vermos. Se n\u00e3o desenvolvermos a vis\u00e3o ampla das coisas como verdadeiramente s\u00e3o, seguiremos com a vis\u00e3o limitada que temos, a vis\u00e3o desde avydia, os seis reinos, o samsara \u2013 o sofrimento duka e a transmigra\u00e7\u00e3o sem fim s\u00e3o os resultados e explicam nossa atual experi\u00eancia de vida. <\/p>\n\n\n\n<p>Aqui o mapa do nosso treinamento at\u00e9 a culmin\u00e2ncia, a extin\u00e7\u00e3o, a frui\u00e7\u00e3o n\u00e3o-dual que permite o movimento naturalmente presente e l\u00facido em todas as circunst\u00e2ncias \u2013 o mapa \u00e9 insuficiente, \u00e9 preciso ser percorrido enquanto trajeto.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758221264%3Fsecret_token%3Ds-SvSS5APQPin&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_13\"><\/a> <u>Cap\u00edtulo 13<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 Vis\u00e3o<\/h3>\n\n\n\n<p>Aqui tomamos como eixo os ensinamentos de Dudjom Rinpoche que est\u00e3o apresentados enquanto o texto \u201cIlumina\u00e7\u00e3o da Sabedoria Primordial\u201d e seguimos at\u00e9 a parte \u201cVis\u00e3o\u201d. Os ensinamentos s\u00e3o apresentados atrav\u00e9s do texto e coment\u00e1rios que clarificam o conte\u00fado dentro da nossa linguagem e conectam a linha tem\u00e1tica das Quatro Nobres Verdades e do Nobre Caminho \u00d3ctuplo do Buda Sakiamuni. O item <em>1. A Prepara\u00e7\u00e3o: Preparando a base, Shamata<\/em> \u00e9 apresentado, onde \u00e9 descrita a pr\u00e1tica e o controle de qualidade correspondente a realiza\u00e7\u00e3o dessa pr\u00e1tica do \u201ccalmo repousar\u201d(shamata). <br><\/p>\n\n\n\n<p>O estudo aborda o item <em>2. A Parte Principal, Gerando a Sabedoria Vipassana<\/em>, em sua primeira parte <em>1. Reconhecer a Vis\u00e3o<\/em>. Essa primeira parte tem tr\u00eas partes tamb\u00e9m, todos abordados at\u00e9 o final:<em> 1. Reconhecer a natureza dos objetos percebidos como externos, 2. Reconhecer a natureza da mente interna que percebe, <\/em>e<em> 3. Reconhecer a vis\u00e3o proveniente do estado natural.<\/em><\/p>\n\n\n\n<p>Culminamos com a apresenta\u00e7\u00e3o de Darmata,\nque \u00e9 a \u201cvis\u00e3o da Grande Perfei\u00e7\u00e3o al\u00e9m da mente ordin\u00e1ria\u201d.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758226037%3Fsecret_token%3Ds-IqRleYXTTdg&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_14\"><\/a> <u>Cap\u00edtulo 14<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Contextualiza\u00e7\u00e3o do Estudo<\/h3>\n\n\n\n<p>Relembramos rapidamente a perspectiva do\nconjunto dos estudos que est\u00e3o sendo apresentadosdentro dessa linha tem\u00e1tica\ndas Quatro Nobres Verdades e do Nobre Caminho de Oito Passos. <\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758226196%3Fsecret_token%3Ds-4P2Dmb3J3XX&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_15\"><\/a> <u>Cap\u00edtulo 15<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Contextualiza\u00e7\u00e3o do Trajeto Percorrido<\/h3>\n\n\n\n<p>Seguimos aqui refletindo sobre o que foi apresentado e os sinais da nossa pr\u00e1tica. O exame das identidades, sua vacuidade e luminosidade, seu surgimento e cessa\u00e7\u00e3o, e o que somos al\u00e9m das identidades. A vis\u00e3o de vacuidade como o Buda apresentou. A import\u00e2ncia da contempla\u00e7\u00e3o e o surgimento da vis\u00e3o. Nascimento no l\u00f3tus com a vis\u00e3o e liberdade do Bodisatva. Os obst\u00e1culos como caminho, sua inseparatividade do ambiente. O princ\u00edpio da lucidez vital de Dorje Drolo e a vis\u00e3o do Buda Sakiamuni. O amadurecimento progressivo da vis\u00e3o que avan\u00e7a nessa dire\u00e7\u00e3o atrav\u00e9s da contempla\u00e7\u00e3o e medita\u00e7\u00e3o.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758238409%3Fsecret_token%3Ds-47LuTQCLGrE&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_16\"><\/a> <u>Cap\u00edtulo 16<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 Medita\u00e7\u00e3o<\/h3>\n\n\n\n<p>Avan\u00e7amos aqui no estudo da linha tem\u00e1tica das Quatro Nobres Verdades e do Nobre Caminho \u00d3ctuplo, seguindo o texto de Dudjom Rinpoche agora no item <em>2. A Parte Principal, Gerando a Sabedoria Vipassana<\/em>, ap\u00f3s vis\u00e3o, entramos agora em medita\u00e7\u00e3o, trazer a vis\u00e3o ao cora\u00e7\u00e3o: <em>2. Traz\u00ea-la ao cora\u00e7\u00e3o atrav\u00e9s da medita\u00e7\u00e3o.<\/em><\/p>\n\n\n\n<p>Come\u00e7amos aqui: &#8220;O passado cessou, o futuro ainda n\u00e3o surgiu, essa presente lucidez Rigpa, nua e vazia \u2013 tome-a como o caminho.&#8221; Finalizamos com a descri\u00e7\u00e3o de zangthal, a experi\u00eancia de abertura que tudo penetra.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758246161%3Fsecret_token%3Ds-Q5pYgZlq2Tw&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_17\"><\/a> <u>Cap\u00edtulo 17 <\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 A\u00e7\u00e3o<\/h3>\n\n\n\n<p>Seguimos o estudo agora com A\u00e7\u00e3o.\nPercorremos aqui o item <em>3. Sustentar sua Continuidade em Meio \u00e0 A\u00e7\u00e3o.<\/em>\nManter lucidez em meio ao contato dos sentidos f\u00edsicos que impulsiona os doze\nelos da origina\u00e7\u00e3o dependente \u2013 esse \u00e9 o desafio.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758248153%3Fsecret_token%3Ds-tu3CyuAnOYR&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_18\"><\/a> <u>Cap\u00edtulo 18<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ilumina\u00e7\u00e3o da Sabedoria Primordial \u2013 Frui\u00e7\u00e3o<\/h3>\n\n\n\n<p>Chegamos aqui \u00e0 parte final dos\nensinamentos, a frui\u00e7\u00e3o sem esfor\u00e7o ou algu\u00e9m que colha qualquer resultado,\nremo\u00e7\u00e3o completa dos obst\u00e1culos, apresenta\u00e7\u00e3o nua e clara da realidade como\nsempre foi, no quarto tempo al\u00e9m dos outros tr\u00eas.<\/p>\n\n\n\n<p>Tendo compreendido e estabilizado a vis\u00e3o ao ponto de haver uma natural frui\u00e7\u00e3o l\u00facida, livre de enganos, centrada em uma experi\u00eancia n\u00e3o constru\u00edda da natural liberdade al\u00e9m das apar\u00eancias, surge agora um desafio de seguir o caminho circular, girando a roda do Darma, e aplicar essa lucidez profunda para iluminar os itens de contempla\u00e7\u00e3o listados pelo Buda no Sutta Satipatthana e no Sutta Anapanasati, que inclui a lucidez com respeito ao corpo, emo\u00e7\u00f5es, disposi\u00e7\u00f5es mentais, etc. Quando se desenvolve tal clareza, os itens apresentados pelo Buda s\u00e3o ent\u00e3o vistos com grande profundidade e entendemos a impossibilidade da realiza\u00e7\u00e3o final sem dedicarmos aten\u00e7\u00e3o a eles \u2013 esse \u00e9 um ponto essencial. Temos agora um giro adicional a percorrer.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758249863%3Fsecret_token%3Ds-SDWDj0cyeZN&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_19\"><\/a> <u> Cap\u00edtulo 19<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A Motiva\u00e7\u00e3o e o Caminho<\/h3>\n\n\n\n<p class=\"has-text-align-right\"><em>O conte\u00fado dos cap\u00edtulos 19 e 20 constitui parte da fala do dia 8 de dezembro, dia da ilumina\u00e7\u00e3o do Buda. Havia muitos visitantes.<\/em>  <em>O Templo do Caminho do Meio estava preenchido com as crian\u00e7as, suas vozes e sua natural manifesta\u00e7\u00e3o luminosa.<\/em> <\/p>\n\n\n\n<p>Ainda n\u00e3o estamos estabilizados no caminho\nde treinamento. Apenas levantamos um v\u00e9u e espiamos adiante. O caminho \u00e9\nabandonado caso a motiva\u00e7\u00e3o n\u00e3o seja clara. Os obst\u00e1culos n\u00e3o s\u00e3o externos e\nnem materiais, mas a motiva\u00e7\u00e3o insuficiente. A ess\u00eancia da motiva\u00e7\u00e3o \u00e9 a vis\u00e3o\nde mundo que brota da vis\u00e3o interna. Essa vis\u00e3o precisa ser suficientemente\nelevada. Havendo motiva\u00e7\u00e3o e vis\u00e3o elevadas, a a\u00e7\u00e3o que o praticante\nempreender\u00e1 o conduzir\u00e1 na dire\u00e7\u00e3o correta at\u00e9 o final do caminho, \u00e0 dissolu\u00e7\u00e3o\ndos obst\u00e1culos e ao lugar de onde nunca hav\u00edamos nos afastado efetivamente em\ntempo algum. Tudo o que foi aqui falado ao longo desses dias perde a for\u00e7a caso\nnossa motiva\u00e7\u00e3o ou vis\u00e3o de mundo sejam insuficientes. Nesse caso, como meu\nmestre diria, pelo menos busque manifestar-se como uma boa pessoa e seus\nm\u00e9ritos se ampliar\u00e3o, suas vidas ser\u00e3o mais felizes e equilibradas e no futuro,\nquando as condi\u00e7\u00f5es amadurecerem, o caminho reaparecer\u00e1.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758250388%3Fsecret_token%3Ds-TnpOxtNJzQA&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>\n\n\n\n<h3><a name=\"capitulo_20\"><\/a> <u>Cap\u00edtulo 20<\/u><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">As Crises Desafiadoras Atuais<\/h3>\n\n\n\n<p>Muitos desafios sempre estiveram\npresentes. Hoje estamos vendo o surgimento generalizado de a\u00e7\u00f5es compassivas e\namplas de auto organiza\u00e7\u00e3o e reencantamento em todas as partes do mundo. O\npensamento estreito e agressivo tem menos capacidade de lidar com as dificuldades\npresentes. A vis\u00e3o ampla \u00e9 melhor, mais forte. Ainda n\u00e3o \u00e9 o tempo de\ndegeneresc\u00eancia como descrito nos ensinamentos do Buda. Os ensinamentos do Buda\nSakiamuni ainda est\u00e3o fortes e capazes de trazer benef\u00edcios.<\/p>\n\n\n\n<i><a href=\"#voltar\"><u>Voltar ao \u00cdndice<\/u><\/a><\/i>\n\n\n\n<iframe scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/758252617%3Fsecret_token%3Ds-PdIR7YX8Wvb&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Nessa linha tem\u00e1tica voc\u00ea encontrar\u00e1 instru\u00e7\u00f5es diretas para ter \u00eaxito no caminho da medita\u00e7\u00e3o e evitar os obst\u00e1culos naturais. Esses \u00e1udios foram gravados durante o retiro da Ilumina\u00e7\u00e3o do Buda de 01 a 08 de dezembro de 2019 no Cebb Caminho do Meio em Viam\u00e3o. O objetivo \u00e9 apoiar os praticantes que, de v\u00e1rios modos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40,254,125,121],"tags":[],"class_list":["post-865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-linha-tematica-especial","category-linhastematicas1","category-meditacao","category-21-itens"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/acaoparamita.com.br\/wp-content\/uploads\/2019\/12\/MG_7983-scaled.jpg?fit=2560%2C1707&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/posts\/865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/comments?post=865"}],"version-history":[{"count":1,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/posts\/865\/revisions"}],"predecessor-version":[{"id":7822,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/posts\/865\/revisions\/7822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media\/926"}],"wp:attachment":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media?parent=865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/categories?post=865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/tags?post=865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}