{"id":19268,"date":"2025-03-24T09:53:40","date_gmt":"2025-03-24T12:53:40","guid":{"rendered":"https:\/\/acaoparamita.com.br\/?post_type=product&#038;p=19268"},"modified":"2025-03-24T10:06:32","modified_gmt":"2025-03-24T13:06:32","slug":"inscricao-para-o-retiro-o-caminho-budista-para-o-equilibrio-social-saude-fisica-e-mental","status":"publish","type":"product","link":"https:\/\/acaoparamita.com.br\/en\/ensinamentos\/inscricao-para-o-retiro-o-caminho-budista-para-o-equilibrio-social-saude-fisica-e-mental\/","title":{"rendered":"Inscri\u00e7\u00e3o para o Retiro &#8220;O Caminho Budista para o Equil\u00edbrio Social, Sa\u00fade F\u00edsica e Mental&#8221; CEBB Floripa | 11 a 13 de abril"},"content":{"rendered":"<p><em>Esta p\u00e1gina \u00e9 referente apenas ao retiro on-line.<\/em><br \/>\n<strong><b>Period: <\/b><\/strong>De 11 a 13 de abril de 2025<br \/>\n<strong>Theme:<\/strong> O Caminho Budista para o Equil\u00edbrio Social, Sa\u00fade F\u00edsica e Mental | CEBB Floripa<\/p>\n<p>Estamos mudando a forma de inscri\u00e7\u00e3o para os estudos, retiros e palestras on-line. Dessa forma, cada pessoa ter\u00e1 um login e uma senha e\u00a0 precisar\u00e1 cadastrar seus dados apenas uma vez. Tamb\u00e9m cada pessoa ter\u00e1 o seu espa\u00e7o para consultar os retiros dos quais j\u00e1 participou. Se voc\u00ea tiver qualquer d\u00favida, pedimos que entre em contato com acaoparamita@gmail.com. Se voc\u00ea n\u00e3o leu os detalhes sobre o evento, <a href=\"https:\/\/cebb.org.br\/lama-floripa-abril25\/\">acesse o site do CEBB.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><strong><b>Contribui\u00e7\u00e3o sugerida e pr\u00e1tica de generosidade<\/b><b>:<br \/>\n<\/b><\/strong>Sua inscri\u00e7\u00e3o e acesso online para o retiro independem de contribui\u00e7\u00e3o financeira. Caso seja poss\u00edvel contribuir, o valor sugerido \u00e9 de R$250,00.<\/p>","protected":false},"featured_media":13300,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[229],"product_tag":[143],"class_list":{"0":"post-19268","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-retiro-floripa-25","7":"product_tag-visibilidade-produto-na-pagina-meu-espaco","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"sold-individually","14":"purchasable","15":"product-type-simple","16":"nyp-product"},"exclude_global_add_ons":[],"addons":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product\/19268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/comments?post=19268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media\/13300"}],"wp:attachment":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media?parent=19268"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=19268"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=19268"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=19268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}