{"id":19415,"date":"2025-03-31T11:45:43","date_gmt":"2025-03-31T14:45:43","guid":{"rendered":"https:\/\/acaoparamita.com.br\/?post_type=product&#038;p=19415"},"modified":"2025-03-31T11:49:16","modified_gmt":"2025-03-31T14:49:16","slug":"palestra-praticas-para-uma-vida-harmoniosa-e-um-cotidiano-lucido","status":"publish","type":"product","link":"https:\/\/acaoparamita.com.br\/en\/ensinamentos\/palestra-praticas-para-uma-vida-harmoniosa-e-um-cotidiano-lucido\/","title":{"rendered":"Palestra &#8220;Pr\u00e1ticas para uma vida harmoniosa e um cotidiano l\u00facido \u2013 conselhos de um Lama brasileiro&#8221; CEBB Crici\u00fama | 22.04"},"content":{"rendered":"<p><em>Esta p\u00e1gina \u00e9 referente apenas ao evento on-line.<\/em><br \/>\n<strong><b>Data: <\/b><\/strong>22 de abril de 2025\u00a0 \u2013 CEBB Crici\u00fama<br \/>\n<strong>Hor\u00e1rio: <\/strong>19h<br \/>\n<strong>Theme:\u00a0<\/strong> Palestra | Pr\u00e1ticas para uma vida harmoniosa e um cotidiano l\u00facido \u2013 conselhos de um Lama brasileiro<\/p>\n<p>Estamos mudando a forma de inscri\u00e7\u00e3o para os estudos, retiros e palestras on-line. Dessa forma, cada pessoa ter\u00e1 um login e uma senha e\u00a0 precisar\u00e1 cadastrar seus dados apenas uma vez. Tamb\u00e9m cada pessoa ter\u00e1 o seu espa\u00e7o para consultar os retiros dos quais j\u00e1 participou. Se voc\u00ea tiver qualquer d\u00favida, pedimos que entre em contato com acaoparamita@gmail.com. Se voc\u00ea n\u00e3o leu os detalhes sobre o evento, <a href=\"https:\/\/cebb.org.br\/palestra-cotidiano-criciuma\/\">acesse o site do CEBB.<\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p><strong><b>Contribui\u00e7\u00e3o sugerida e pr\u00e1tica de generosidade<\/b><b>:<br \/>\n<\/b><\/strong>Sua inscri\u00e7\u00e3o e acesso online para o retiro independem de contribui\u00e7\u00e3o financeira.<\/p>","protected":false},"featured_media":14721,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[232],"product_tag":[143],"class_list":{"0":"post-19415","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-palestra-criciuma-25","7":"product_tag-visibilidade-produto-na-pagina-meu-espaco","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"sold-individually","14":"purchasable","15":"product-type-simple","16":"nyp-product"},"exclude_global_add_ons":[],"addons":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product\/19415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/comments?post=19415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media\/14721"}],"wp:attachment":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media?parent=19415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=19415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=19415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=19415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}