{"id":20522,"date":"2025-05-14T11:26:02","date_gmt":"2025-05-14T14:26:02","guid":{"rendered":"https:\/\/acaoparamita.com.br\/?post_type=product&#038;p=20522"},"modified":"2025-05-16T17:41:38","modified_gmt":"2025-05-16T20:41:38","slug":"inscricao-retiro-para-reencantar-a-vida-cotidiana-e-agir-com-sabedoria","status":"publish","type":"product","link":"https:\/\/acaoparamita.com.br\/en\/ensinamentos\/inscricao-retiro-para-reencantar-a-vida-cotidiana-e-agir-com-sabedoria\/","title":{"rendered":"Retiro &#8220;Para reencantar a vida cotidiana e agir com sabedoria&#8221; &#8211; CEBB Londrina | 30 de maio a 1 de junho"},"content":{"rendered":"<p><em>Esta p\u00e1gina \u00e9 referente apenas ao retiro on-line.<\/em><br \/>\n<strong><b>Period: <\/b><\/strong>De 30 de maio a 1 de junho de 2025<br \/>\n<strong>Theme:<\/strong> Para reencantar a vida cotidiana e agir com sabedoria | CEBB Londrina<\/p>\n<p>Estamos mudando a forma de inscri\u00e7\u00e3o para os estudos, retiros e palestras on-line. Dessa forma, cada pessoa ter\u00e1 um login e uma senha e\u00a0 precisar\u00e1 cadastrar seus dados apenas uma vez. Tamb\u00e9m cada pessoa ter\u00e1 o seu espa\u00e7o para consultar os retiros dos quais j\u00e1 participou. Se voc\u00ea tiver qualquer d\u00favida, pedimos que entre em contato com acaoparamita@gmail.com. Se voc\u00ea n\u00e3o leu os detalhes sobre o evento, <a href=\"https:\/\/cebb.org.br\/retiro-para-reencantar-a-vida-cotidiana-e-agir-com-sabedoria-cebb-londrina\">acesse o site do CEBB<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong><b>Contribui\u00e7\u00e3o sugerida e pr\u00e1tica de generosidade<\/b><b>:<br \/>\n<\/b><\/strong>Sua inscri\u00e7\u00e3o e acesso online para o retiro independem de contribui\u00e7\u00e3o financeira. Caso seja poss\u00edvel contribuir, o valor sugerido \u00e9 de R$250,00.<\/p>","protected":false},"featured_media":13300,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[239],"product_tag":[143],"class_list":{"0":"post-20522","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-retiro-cebb-londrina","7":"product_tag-visibilidade-produto-na-pagina-meu-espaco","9":"first","10":"instock","11":"downloadable","12":"virtual","13":"purchasable","14":"product-type-simple","15":"nyp-product"},"exclude_global_add_ons":[],"addons":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product\/20522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/comments?post=20522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media\/13300"}],"wp:attachment":[{"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/media?parent=20522"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=20522"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=20522"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/acaoparamita.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=20522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}